{"id":192,"date":"2025-04-09T09:25:44","date_gmt":"2025-04-08T23:25:44","guid":{"rendered":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/?page_id=192"},"modified":"2025-04-09T16:04:19","modified_gmt":"2025-04-09T06:04:19","slug":"travel-illnesses","status":"publish","type":"page","link":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/travel-illnesses\/","title":{"rendered":"Travel Illnesses"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-192","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Travel Illnesses | Ochre Medical Centre Kotara<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travel Illnesses | Ochre Medical Centre Kotara\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/travel-illnesses\/\" \/>\n<meta property=\"og:site_name\" content=\"Kotara\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-09T06:04:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ochrehealth.com.au\\\/medical-centre-kotara\\\/travel-illnesses\\\/\",\"url\":\"https:\\\/\\\/ochrehealth.com.au\\\/medical-centre-kotara\\\/travel-illnesses\\\/\",\"name\":\"Travel Illnesses | Ochre Medical Centre Kotara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ochrehealth.com.au\\\/medical-centre-kotara\\\/#website\"},\"datePublished\":\"2025-04-08T23:25:44+00:00\",\"dateModified\":\"2025-04-09T06:04:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ochrehealth.com.au\\\/medical-centre-kotara\\\/travel-illnesses\\\/#breadcrumb\"},\"inLanguage\":\"en-AU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ochrehealth.com.au\\\/medical-centre-kotara\\\/travel-illnesses\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ochrehealth.com.au\\\/medical-centre-kotara\\\/travel-illnesses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ochrehealth.com.au\\\/medical-centre-kotara\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travel Illnesses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ochrehealth.com.au\\\/medical-centre-kotara\\\/#website\",\"url\":\"https:\\\/\\\/ochrehealth.com.au\\\/medical-centre-kotara\\\/\",\"name\":\"Kotara\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ochrehealth.com.au\\\/medical-centre-kotara\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-AU\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Travel Illnesses | Ochre Medical Centre Kotara","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Travel Illnesses | Ochre Medical Centre Kotara","og_url":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/travel-illnesses\/","og_site_name":"Kotara","article_modified_time":"2025-04-09T06:04:19+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/travel-illnesses\/","url":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/travel-illnesses\/","name":"Travel Illnesses | Ochre Medical Centre Kotara","isPartOf":{"@id":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/#website"},"datePublished":"2025-04-08T23:25:44+00:00","dateModified":"2025-04-09T06:04:19+00:00","breadcrumb":{"@id":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/travel-illnesses\/#breadcrumb"},"inLanguage":"en-AU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ochrehealth.com.au\/medical-centre-kotara\/travel-illnesses\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/travel-illnesses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/"},{"@type":"ListItem","position":2,"name":"Travel Illnesses"}]},{"@type":"WebSite","@id":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/#website","url":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/","name":"Kotara","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-AU"}]}},"_links":{"self":[{"href":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/wp-json\/wp\/v2\/pages\/192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/wp-json\/wp\/v2\/comments?post=192"}],"version-history":[{"count":3,"href":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/wp-json\/wp\/v2\/pages\/192\/revisions"}],"predecessor-version":[{"id":218,"href":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/wp-json\/wp\/v2\/pages\/192\/revisions\/218"}],"wp:attachment":[{"href":"https:\/\/ochrehealth.com.au\/medical-centre-kotara\/wp-json\/wp\/v2\/media?parent=192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}